{"id":1670,"date":"2023-11-17T12:29:49","date_gmt":"2023-11-17T11:29:49","guid":{"rendered":"https:\/\/produktpass-teppichboden.de\/wissenswertes\/"},"modified":"2024-01-22T13:02:34","modified_gmt":"2024-01-22T12:02:34","slug":"informations-utiles","status":"publish","type":"page","link":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/","title":{"rendered":"informations-utiles"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(10,0,0,0.28)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/GUT_Gemeinschaft_umweltfreundlicher_Teppichboeden_ev_header2.jpg\u00a0\u00bb background_position=\u00a0\u00bbbottom_center\u00a0\u00bb background_vertical_offset=\u00a0\u00bb20%\u00a0\u00bb background_blend=\u00a0\u00bbmultiply\u00a0\u00bb height=\u00a0\u00bb32vh\u00a0\u00bb height_tablet=\u00a0\u00bb32vh\u00a0\u00bb height_phone=\u00a0\u00bb36vh\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb min_height=\u00a0\u00bb100%\u00a0\u00bb height=\u00a0\u00bb100%\u00a0\u00bb max_height=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_line_height=\u00a0\u00bb1.1em\u00a0\u00bb custom_margin=\u00a0\u00bb10vh||8px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb7vh||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb7vh||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Informations utiles<br \/>sur les moquettes<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(10,0,0,0.05)\u00a0\u00bb custom_padding=\u00a0\u00bb34px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb#arten\u00a0\u00bb button_text=\u00a0\u00bbTypes\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb#piktogramme\u00a0\u00bb button_text=\u00a0\u00bbPictogrammes\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb#auswahl\u00a0\u00bb button_text=\u00a0\u00bbS\u00e9lection\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb#ce-kennzeichnung\u00a0\u00bb button_text=\u00a0\u00bbMarquage CE\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb#reinigung\u00a0\u00bb button_text=\u00a0\u00bbEntretien et nettoyage\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb module_class=\u00a0\u00bb#reinigung\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb#abkuerzungen\u00a0\u00bb button_text=\u00a0\u00bbR\u00e9pertoire des Abr\u00e9viations\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3FA535&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb35px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_css_main_element=\u00a0\u00bbwidth: 100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#154689&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb31px||8px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>D\u00e9couvrez ici des informations importantes sur les rev\u00eatements de sol textiles : pour le choix d\u2019une moquette ad\u00e9quate, sur le nettoyage et l&rsquo;entretien ainsi que sur le march\u00e9 des moquettes dans l&rsquo;Union europ\u00e9enne.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00a0\u00bbarten\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#23295B\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Types de moquettes<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Rev\u00eatements de sol textiles<\/h3>\n<p>Les moquettes sont des rev\u00eatements de sol textiles. Selon la norme DIN ISO 2424, ce sont des produits qui comportent une couche d\u2019usage en fibres textiles et qui sont g\u00e9n\u00e9ralement utilis\u00e9s pour recouvrir le sol. Il existe divers types de moquettes pour divers domaines d&rsquo;application.<\/p>\n<p><strong>Moquette:<\/strong><br \/>La moquette est un rev\u00eatement de sol textile qui recouvre g\u00e9n\u00e9ralement toute la surface d\u2019une pi\u00e8ce. Ces moquettes sont \u00e9galement appel\u00e9es tapis plains ou rev\u00eatements de sol textiles mur \u00e0 mur.<\/p>\n<p><strong>Tapis:<\/strong><br \/>Un tapis est un rev\u00eatement de sol textile de forme et de dimension fixes.<\/p>\n<p><strong>Tapis de couloir:<\/strong><br \/>Un tapis de couloir est un tapis long et \u00e9troit que l&rsquo;on trouve souvent dans les couloirs. Ce type de tapis est souvent pos\u00e9 sur les voies de passage.<\/p>\n<p><strong>Dalles de moquette:<\/strong><br \/>Les dalles de moquette sont des rev\u00eatements de sol textiles qui recouvrent la surface d\u2019une pi\u00e8ce sous forme de carr\u00e9s ou de rectangles assembl\u00e9s.<br \/>Autres possibilit\u00e9s de distinction des moquettes<br \/>Les rev\u00eatements de sol textiles peuvent \u00eatre diff\u00e9renci\u00e9s selon d&rsquo;autres crit\u00e8res, qui sont \u00e9num\u00e9r\u00e9s ci-dessous.<\/p>\n<p><strong>Proc\u00e9d\u00e9s de fabrication de moquettes :<\/strong><\/p>\n<ul>\n<li>Moquette tiss\u00e9e<\/li>\n<li>Moquette tuft\u00e9e<\/li>\n<li>Moquette aiguillet\u00e9e<\/li>\n<li>Textile floqu\u00e9<\/li>\n<li>Moquette \u00e0 points nou\u00e9s<\/li>\n<\/ul>\n<p><strong>Selon la structure de la couche d\u2019usage, on distingue:<\/strong><\/p>\n<ul>\n<li>Moquette \u00e0 velours<\/li>\n<li>Moquette plate<\/li>\n<\/ul>\n<p><strong>Les mat\u00e9riaux utilis\u00e9s pour la fabrication de la couche d\u2019usage peut \u00eatre r\u00e9partis grosso modo en:<\/strong><\/p>\n<ul>\n<li>Fibres naturelles<\/li>\n<li>Fibres synth\u00e9tiques<\/li>\n<\/ul>\n<p><strong>On diff\u00e9rencie \u00e9galement les rev\u00eatements de sol textiles selon leur domaine d&rsquo;application:<\/strong><\/p>\n<ul>\n<li>Secteurs priv\u00e9s<\/li>\n<li>Secteurs professionnels<\/li>\n<\/ul>\n<p>Les rev\u00eatements d\u00e9sign\u00e9s comme secondaires sont les tapis, les tapis de couloir et les paillassons qui pr\u00e9sentent des bordages ou des bords remaill\u00e9s.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00a0\u00bbauswahl\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#23295B\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>S\u00e9lection des moquettes<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Pour effectuer le choix du rev\u00eatement de sol textile appropri\u00e9 pour votre domaine d\u2019application, vous pouvez vous r\u00e9f\u00e9rer aux questions et caract\u00e9ristiques suivantes. Laissez-vous \u00e9galement conseiller par votre revendeur sp\u00e9cialis\u00e9.<\/p>\n<p><strong>1. Domaine d\u2019application<\/strong><br \/>La moquette doit imp\u00e9rativement \u00eatre adapt\u00e9e au domaine d&rsquo;application et r\u00e9pondre aux exigences d&rsquo;utilisation et de durabilit\u00e9 qui en d\u00e9coulent. Il convient de distinguer fondamentalement<\/p>\n<ul>\n<li>le secteur priv\u00e9 et<\/li>\n<li>le secteur professionnel.<\/li>\n<\/ul>\n<p>Les pictogrammes normalis\u00e9s repr\u00e9sent\u00e9s plus loin sur cette page web constituent une bonne r\u00e9f\u00e9rence \u00e0 cet effet.<\/p>\n<p><strong>2. Le confort que doit apporter le rev\u00eatement de sol textile<\/strong><br \/>En termes de confort, c.-\u00e0-d. la structure de la couche d\u2019usage, sa douceur et son niveau de caract\u00e8re agr\u00e9able, les moquettes sont class\u00e9es en cinq classes de confort. Le classement est \u00e9galement repr\u00e9sent\u00e9 visuellement par des \u00ab couronnes \u00bb dont le nombre augmente avec le niveau de confort. Le confort est \u00e9galement repr\u00e9sent\u00e9 par des pictogrammes normalis\u00e9s. Pour en savoir plus, cliquez ici.<\/p>\n<p><strong>3. Exigences compl\u00e9mentaires ou aptitudes sp\u00e9cifiques<\/strong><br \/>Les rev\u00eatements de sol textiles doivent r\u00e9pondre \u00e0 un certain nombre d\u2019exigences suppl\u00e9mentaires en fonction de leur environnement d&rsquo;utilisation. De l&rsquo;aptitude \u00e0 l\u2019utilisation pour des si\u00e8ges \u00e0 roulettes, en passant par les aspects de s\u00e9curit\u00e9 comme, entre autres, les propri\u00e9t\u00e9s antid\u00e9rapantes ou les classe de r\u00e9sistance au feu, jusqu\u2019\u00e0 l&rsquo;aptitude \u00e0 la pose sur des sols \u00e9quip\u00e9s de syst\u00e8mes chauffants. Pour obtenir les informations n\u00e9cessaires pour savoir si une moquette est adapt\u00e9e au domaine d\u2019application respectif ou \u00e0 la pi\u00e8ce et\/ou \u00e0 l&rsquo;environnement d\u2019utilisation, vous pouvez consulter votre revendeur sp\u00e9cialis\u00e9 mais aussi les pictogrammes qui mentionnent l&rsquo;aptitude compl\u00e9mentaire respective du rev\u00eatement de sol.<\/p>\n<p><strong>4. La durabilit\u00e9<\/strong><br \/>L\u2019aspect de la durabilit\u00e9 peut (\u00e9galement) \u00eatre pris en compte pour l\u2019\u00e9valuation d\u2019un rev\u00eatement de sol textile. Les trois dimensions fondamentales pour le choix d\u2019un rev\u00eatement de sol textile regroupent les crit\u00e8res suivants:<\/p>\n<p>La dimension \u00e9conomique<\/p>\n<ul>\n<li>Co\u00fbts d&rsquo;acquisition (co\u00fbts du produit et de la pose), co\u00fbts pendant l&rsquo;utilisation (entretien et maintenance) et co\u00fbts de retrait (\u00e9limination \/ recyclage)<\/li>\n<\/ul>\n<p>La dimension \u00e9cologique<\/p>\n<ul>\n<li>Dans cette dimension, on \u00e9value les impacts environnementaux comme, entre autres, le m\u00e9nagement des ressources et la consommation d&rsquo;\u00e9nergie sur la base d\u2019examens et de tests de divers aspects de la production, de la pose, de l&rsquo;utilisation ainsi que de l&rsquo;\u00e9limination et\/ou du recyclage.<\/li>\n<\/ul>\n<p>Dimension sociale et culturelle<\/p>\n<ul>\n<li>La prise en consid\u00e9ration de la dimension sociale et culturelle de la durabilit\u00e9 concerne les domaines de l&rsquo;esth\u00e9tique, de l\u2019am\u00e9nagement, de l&rsquo;accessibilit\u00e9 et les aspects de protection de la sant\u00e9 et du confort.<\/li>\n<\/ul>\n<p>Pour en savoir plus sur le th\u00e8me de la durabilit\u00e9, nous vous prions de vous reporter \u00e0 notre page \u00ab Construction durable \u00bb.<\/p>\n<p><strong>5. Une qualit\u00e9 certifi\u00e9e par le label GUT ou le passeport produit PRODIS de l\u2019association GUT<\/strong><br \/>Le plus important pour prendre une d\u00e9cision en faveur d\u2019un rev\u00eatement de sol textile appropri\u00e9 ou r\u00e9pondant aux besoins sp\u00e9cifiques est la possibilit\u00e9 d\u2019acc\u00e9der \u00e0 des informations transparentes et exhaustives sur les caract\u00e9ristiques du produit. Toutes ces informations sont disponibles dans le passeport produit GUT-PRODIS pour les rev\u00eatements de sol textiles.<\/p>\n<p>Le passeport produit GUT-PRODIS vous fournit toutes les informations n\u00e9cessaires sur toutes les caract\u00e9ristiques techniques et environnementales d&rsquo;une moquette. Ces informations essentielles disponibles directement en ligne vous fournissent des donn\u00e9es pr\u00e9cises sur les mat\u00e9riaux, produits chimiques et traitements utilis\u00e9s pour la production ainsi qu&rsquo;une d\u00e9claration environnementale de produit.<\/p>\n<p>Le label GUT est un gage de s\u00e9curit\u00e9 fondamentale : le label GUT est uniquement attribu\u00e9 aux produits qui r\u00e9pondent \u00e0 nos s\u00e9v\u00e8res crit\u00e8res de test. Pour en savoir plus, rendez-vous sur notre page Test de produit.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00a0\u00bbreinigung\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#23295B\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Nettoyage et entretien des rev\u00eatements de sol textiles<\/h2>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=\u00a0\u00bb29px\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb ul_line_height=\u00a0\u00bb1.6em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Pour pr\u00e9server aussi longtemps que possible les caract\u00e9ristiques esth\u00e9tiques et fonctionnelles d&rsquo;un rev\u00eatement de sol textile, un nettoyage et un entretien r\u00e9guliers et corrects sont indispensables. Dans ce contexte, il convient de prendre en compte le mat\u00e9riau, la structure, le dossier ainsi que la m\u00e9thode de pose du rev\u00eatement de sol. Le nettoyage et l&rsquo;entretien doivent de mani\u00e8re g\u00e9n\u00e9rale \u00eatre effectu\u00e9s conform\u00e9ment aux instructions du fabricant pour pr\u00e9server les droits de garantie en cas de r\u00e9clamation. Votre revendeur sp\u00e9cialis\u00e9 sera \u00e9galement ravi de vous fournir davantage d\u2019informations sur ce sujet.<\/p>\n<p><strong>Entretien pr\u00e9ventif<\/strong><\/p>\n<p>Prot\u00e9gez \u00e0 tout moment votre rev\u00eatement de sol textile contre une forte p\u00e9n\u00e9tration salissures de mani\u00e8re pr\u00e9ventive. Il convient en outre de passer r\u00e9guli\u00e8rement (en fonction de l\u2019usage) l\u2019aspirateur \u00e0 brosse. La couche d\u2019usage de la moquette et\/ou les fibres ou le velours sont ainsi redress\u00e9s et cela permet aussi d\u2019\u00e9viter la formation des traces typiques de passages.<\/p>\n<p><strong>\u00c9limination des taches sur les moquettes<\/strong><\/p>\n<p>Les taches sur les moquettes font partie des probl\u00e8mes courants. La r\u00e8gle suivante s\u2019applique de mani\u00e8re g\u00e9n\u00e9rale pour l\u2019\u00e9limination des taches : plus la tache est \u00e9limin\u00e9e rapidement, plus il est probable qu&rsquo;elle puisse \u00eatre \u00e9limin\u00e9e compl\u00e8tement. Les taches et les salissures sur les rev\u00eatements de sol textiles peuvent dans la plupart des cas \u00eatre trait\u00e9es et \u00e9limin\u00e9es avec de l&rsquo;eau chaude et un chiffon absorbant (par ex. un chiffon blanc en coton ou un gant en microfibre). Le plus important pour une telle op\u00e9ration est de ne pas frotter la zone souill\u00e9e avec le chiffon, mais par contre d\u2019\u00e9liminer la tache de l&rsquo;int\u00e9rieur vers l&rsquo;ext\u00e9rieur en appliquant une l\u00e9g\u00e8re pression \u00ab tournante \u00bb. Avant d&rsquo;utiliser un d\u00e9tergent, renseignez-vous d\u2019abord chez le fabricant ou le revendeur sp\u00e9cialis\u00e9 de votre rev\u00eatement de sol textile pour utiliser un produit de nettoyage qui convient pour la moquette correspondante ainsi que pour le type de tache \u00e0 enlever. L\u2019utilisation de d\u00e9tergents inappropri\u00e9s ainsi qu&rsquo;une utilisation incorrecte peuvent causer des dommages irr\u00e9versibles sur votre rev\u00eatement de sol textile.<\/p>\n<p>&nbsp;<\/p>\n<p>En raison de la grande diversit\u00e9 des rev\u00eatements de sol textiles disponibles sur le march\u00e9 et des diverses m\u00e9thodes de nettoyage, nous pouvons seulement vous pr\u00e9senter un aper\u00e7u ici. Nous vous prions de vous renseigner aupr\u00e8s du fabricant ou de votre revendeur sp\u00e9cialis\u00e9 sur la m\u00e9thode correcte de nettoyage, sur les produits de nettoyage et sur les machines pour nettoyer votre moquette correctement. Pour le nettoyage de fond et intensif des rev\u00eatements de sol textiles, nous pouvons vous citer les m\u00e9thodes suivantes :<\/p>\n<ul>\n<li>Nettoyage \u00e0 la mousse s\u00e8che<\/li>\n<li>Nettoyage \u00e0 la poudre<\/li>\n<li>Nettoyage avec pad<\/li>\n<li>Nettoyage par injection-extraction<\/li>\n<li>Combinaison de proc\u00e9d\u00e9s de nettoyage pr\u00e9cit\u00e9s<\/li>\n<li>Proc\u00e9d\u00e9 de nettoyage thermo\u00e9lectrique pour moquettes<\/li>\n<\/ul>\n<p><strong>Utilisation durable des moquettes<\/strong><\/p>\n<p>La durabilit\u00e9 des rev\u00eatements de sol textiles d\u00e9bute en principe d\u00e8s la s\u00e9lection du type de moquette ad\u00e9quat, des mat\u00e9riaux qui la composent, de la structure et de la couleur. Questions importantes \u00e0 clarifier avant de choisir un rev\u00eatement de sol textile:<\/p>\n<ul>\n<li>Est-ce que la zone destin\u00e9e \u00e0 la pose de la moquette est expos\u00e9e \u00e0 une haute fr\u00e9quentation, c.-\u00e0-d. \u00e0 un niveau d\u2019utilisation \u00e9lev\u00e9 ? Est-ce un endroit o\u00f9 la salet\u00e9 est souvent rapport\u00e9e de l&rsquo;ext\u00e9rieur?<\/li>\n<li>Est-ce que le rev\u00eatement de sol textile est expos\u00e9 \u00e0 un niveau d&rsquo;utilisation particuli\u00e8rement \u00e9lev\u00e9? Par exemple, avec des si\u00e8ges \u00e0 roulettes ou au bureau.<\/li>\n<\/ul>\n<p>Pour une longue pr\u00e9servation de la qualit\u00e9 de la moquette associ\u00e9e \u00e0 un m\u00e9nagement des ressources, il convient de se conformer \u00e0 un programme de nettoyage et d&rsquo;entretien coordonn\u00e9 et r\u00e9gulier. Dans l\u2019esprit de la durabilit\u00e9, il faut veiller \u00e0 ce que les m\u00e9thodes utilis\u00e9es et surtout les produits de nettoyage soient \u00e9cocompatibles:<\/p>\n<ul>\n<li>Les m\u00e9thodes qui utilisent le moins de ressources pour un m\u00eame effet de nettoyage.<\/li>\n<li>Utiliser le moins possible de d\u00e9tergents chimiques<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbpiktogramme\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row module_id=\u00a0\u00bbpiktogramme\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb1px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#23295B\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Pictogrammes et leurs significations<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>\u00c0 l&rsquo;instar des rev\u00eatements de sol souples et stratifi\u00e9s, les rev\u00eatements de sol textiles sont affect\u00e9s \u00e0 des classes d\u2019usage selon leurs caract\u00e9ristiques. Pour illustrer ces classes et caract\u00e9ristiques d&rsquo;une mani\u00e8re facilement compr\u00e9hensible, on a cr\u00e9\u00e9 les symboles graphiques FCSS pour les rev\u00eatements de sol (FCSS = Floor Covering Standard Symbols,\u00a0<a href=\"http:\/\/www.floorsymbols.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">floorsymbols.com<\/a>). Vous trouverez ci-dessous un aper\u00e7u de ces classes et des pictogrammes correspondants.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"sppb-addon-title\">Classe d\u2019usage: secteur priv\u00e9 ou professionnel<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Les moquettes sont fondamentalement subdivis\u00e9es pour l\u2019usage domestique et pour l\u2019usage commercial (b\u00e2timents professionnels et publics). La diff\u00e9rence est justifi\u00e9e par l\u2019usage beaucoup plus important dans le secteur commercial comme, entre autres, dans les bureaux ou les h\u00f4tels.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Classes d\u2019usage pour l\u2019usage domestique<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-21.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-21&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe\u00a021<\/strong><\/p>\n<p>Pour zones \u00e0 usage faible ou p\u00e9riodique (l\u00e9ger \u00e0 mod\u00e9r\u00e9)\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-22.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-22&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe 22<\/strong>\u00a0<br \/>Pour zones \u00e1 usage moyen (normal)<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-23.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-23&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe 23\u00a0<br \/><\/strong>Pour zones \u00e0 usage intensif (\u00e9lev\u00e9)<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Classes d\u2019usage pour les b\u00e2timents professionnels et publics<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-31.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-31&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe 31\u00a0<br \/><\/strong>Pour zones \u00e0 usage commercial normal<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-32.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-32&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe 32\u00a0<br \/><\/strong>Pour zones \u00e0 moyenne fr\u00e9quentation du public<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-class-33.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-class-33&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe 33\u00a0<br \/><\/strong>Pour zones \u00e0 moyenne fr\u00e9quentation du public<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Niveaux de confort pour rev\u00eatements de sol textiles<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Au sein des deux classes d&rsquo;usage d\u00e9crites pr\u00e9c\u00e9demment, les moquettes sont encore une fois subdivis\u00e9es selon les classes de confort (LC = Luxury Class\u00a0; EN). Ces classes sont des indicateurs de confort qui se r\u00e9f\u00e8rent \u00e0 la surface du tapis, notamment \u00e0 la douceur et \u00e0 l\u2019aspect agr\u00e9able de celle-ci. Le confort est d\u2019autant plus important que le nombre de \u00ab\u00a0couronnes\u00a0\u00bb est \u00e9lev\u00e9.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,1_5,1_5,1_5,1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-luxury-class-lc1.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-luxury-class-lc1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe LC 1\u00a0<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-luxury-class-lc2.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-luxury-class-lc2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe LC 2<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-luxury-class-lc3.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-luxury-class-lc3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe LC 3\u00a0<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-luxury-class-lc4.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-luxury-class-lc4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe LC 4<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-luxury-class-lc5.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-luxury-class-lc5&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe LC 5<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"sppb-addon-title\">Autres aptitudes additionnelles<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Aptitude pour les roulettes de si\u00e8ges<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La pr\u00e9sence de si\u00e8ges de bureau repr\u00e9sente des contraintes extr\u00eames pour le velours de la moquette. Ces symboles peuvent uniquement \u00eatre utilis\u00e9s pour des moquettes qui ont pass\u00e9 avec succ\u00e8s le test sp\u00e9cial d\u2019aptitude aux roulettes de si\u00e8ge et qui sont ainsi appropri\u00e9es pour une pose dans un bureau (priv\u00e9 ou commercial).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-castor-chair-occasional-use.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-castor-chair-occasional-use\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Usage occasionnel<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-castor-chair-continuous-use.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-castor-chair-continuous-use\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Usage fr\u00e9quent<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Aptitude pour escalier<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Lors de l&rsquo;utilisation de moquettes sur les marches d&rsquo;escalier, les zones situ\u00e9es exactement sur les bords des marches sont soumises \u00e0 de fortes sollicitations. Seuls les produits comportant un des deux symboles suivants sont appropri\u00e9s pour la pose et l\u2019utilisation sur des escaliers.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-stairs-occasional-use.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-stairs-occasional-use\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Usage occasionnel<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-stairs-continuous-use.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-stairs-continuous-use\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Usage fr\u00e9quent<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Bord coup\u00e9<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Ce symbole indique que les bords coup\u00e9s du rev\u00eatement de sol textile ne s&rsquo;effilochent pas, ce qui est particuli\u00e8rement important pour les tapis \u00e0 velours boucl\u00e9.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-resistance-to-fraying.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-resistance-to-fraying\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb20%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Stabilit\u00e9 \u00e0 la lumi\u00e8re \/ R\u00e9flexion de la lumi\u00e8re<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>L&rsquo;exposition directe ou indirecte \u00e0 la lumi\u00e8re (principalement la lumi\u00e8re du soleil) peut entra\u00eener un estompement des couleurs. Le pictogramme repr\u00e9sent\u00e9 ici caract\u00e9rise le produit respectif qui r\u00e9pond aux exigences de base en mati\u00e8re de stabilit\u00e9 \u00e0 la lumi\u00e8re (\u22655, pour les teintes pastel \u22654) selon la m\u00e9thode d&rsquo;essai EN\u00a0ISO\u00a0105-B02.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-light-fastness.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-light-fastness\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Stabilit\u00e9 \u00e0 la lumi\u00e8re<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-light-reflection.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-light-reflection\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>R\u00e9flexion de la lumi\u00e8re<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Propri\u00e9t\u00e9s acoustiques \/ Absorption acoustique<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Ce symbole peut \u00eatre utilis\u00e9 si l&rsquo;absorption acoustique du rev\u00eatement de sol textile a \u00e9t\u00e9 d\u00e9termin\u00e9e conform\u00e9ment \u00e0 la norme applicable. La valeur d&rsquo;absorption d\u00e9termin\u00e9e doit \u00eatre indiqu\u00e9e sur la fiche technique correspondante du produit, ce qui s&rsquo;applique aux caract\u00e9ristiques g\u00e9n\u00e9rales ainsi qu&rsquo;\u00e0 l&rsquo;absorption des bruits d&rsquo;impact et \u00e0 la r\u00e9duction des bruits de chocs. De mani\u00e8re g\u00e9n\u00e9rale, on peut dire que les rev\u00eatements de sol textiles poss\u00e8dent souvent de bonnes propri\u00e9t\u00e9s d\u2019absorption des bruits d&rsquo;impact et d&rsquo;isolation acoustique.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-acoustical-sound-absorption.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-acoustical-sound-absorption\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Absorption acoustique,<br \/><\/strong><strong>indication en db<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-acoustical-walking-noise.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-acoustical-walking-noise\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Absorption des bruits d\u2019impact,<\/strong><br \/><strong>indication en db<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-acoustical-impact-noise-reduction.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-acoustical-impact-noise-reduction\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>R\u00e9duction des bruits de chocs,<\/strong><br \/><strong>indication en db<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"sppb-addon-title\">Pictogrammes du marquage CE de rev\u00eatements de sol textiles<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Outre les affectations de base en classes d&rsquo;usage et de niveaux de confort, les rev\u00eatements de sol textiles sont \u00e9galement caract\u00e9ris\u00e9s par des symboles graphiques (pictogrammes) qui indiquent des caract\u00e9ristiques compl\u00e9mentaires pour l\u2019environnement d&rsquo;utilisation et\/ou des aptitudes additionnelles. Certaines de ces aptitudes sont soumises aux r\u00e9f\u00e9rentiels et\/ou aux exigences du R\u00e8glement Produits de Construction et doivent \u00eatre mentionn\u00e9es dans la d\u00e9claration des performances, \u00e0 laquelle se r\u00e9f\u00e8re le marquage CE. Ces caract\u00e9ristiques sont mentionn\u00e9es dans les sections suivantes.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00a0\u00bbce-kennzeichnung\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Obligation d\u2019apposition du marquage CE<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div>En Europe, les rev\u00eatements de sol textiles doivent porter un marquage dit \u00ab\u00a0CE\u00a0\u00bb. L&rsquo;abr\u00e9viation \u00ab\u00a0CE\u00a0\u00bb n&rsquo;a pas de signification uniform\u00e9ment d\u00e9finie, mais est d\u00e9sign\u00e9e par \u00ab\u00a0Certified Europe\u00a0\u00bb (EN) ou \u00ab\u00a0Conformit\u00e9 Europ\u00e9enne\u00a0\u00bb (FR) et vise \u00e0 d\u00e9finir la conformit\u00e9 du produit en ce qui concerne les exigences relatives aux caract\u00e9ristiques du produit: sant\u00e9, s\u00e9curit\u00e9 et \u00e9conomie d&rsquo;\u00e9nergie. Le marquage CE doit \u00eatre appos\u00e9 sur l&#8217;emballage et dans les fiches techniques ou la d\u00e9claration de performance du tapis. Sans le marquage CE &#8211; et sans le respect des sp\u00e9cifications &#8211; les produits ne peuvent pas \u00eatre commercialis\u00e9s dans l&rsquo;UE.<\/div>\n<div>Les modalit\u00e9s d&rsquo;essai et d&rsquo;\u00e9tiquetage des rev\u00eatements de sol textiles sont d\u00e9finies dans la norme harmonis\u00e9e EN 14041. En Allemagne, cette directive europ\u00e9enne a \u00e9t\u00e9 mise en \u0153uvre avec la loi sur les produits de construction. Les exigences sp\u00e9cifiques aux produits portent sur les crit\u00e8res suivants:<\/div>\n<div>\n<ul>\n<li>comportement au feu\/ protection contre l&rsquo;incendie<\/li>\n<li>la r\u00e9sistance m\u00e9canique et la stabilit\u00e9<\/li>\n<li>l&rsquo;hygi\u00e8ne, la sant\u00e9 et la protection de l&rsquo;environnement<\/li>\n<li>la s\u00e9curit\u00e9 d&rsquo;utilisation<\/li>\n<li>Isolation acoustique<\/li>\n<li>les \u00e9conomies d&rsquo;\u00e9nergie et l&rsquo;isolation thermique<\/li>\n<\/ul>\n<\/div>\n<div>Dans le domaine des rev\u00eatements de sol, ces exigences ont \u00e9t\u00e9 r\u00e9sum\u00e9es dans les propri\u00e9t\u00e9s essentielles suivantes, dont la d\u00e9claration ne peut \u00eatre faite que dans le cadre du marquage CE. Les informations respectives du fabricant figurent alors \u00e0 la fois sur l&rsquo;\u00e9tiquette CE et sur la d\u00e9claration de performance qui, outre les propri\u00e9t\u00e9s d\u00e9clar\u00e9es du produit, doit \u00e9galement contenir l&rsquo;adresse du fabricant et la signature d&rsquo;une personne responsable. Les informations figurant sur le label CE et dans la d\u00e9claration de performance doivent \u00eatre identiques.<\/div>\n<div>Au moins une caract\u00e9ristique essentielle doit \u00eatre d\u00e9clar\u00e9e. Sur la base des propri\u00e9t\u00e9s d\u00e9clar\u00e9es, il est possible de d\u00e9terminer si le produit de construction peut \u00eatre install\u00e9 dans le b\u00e2timent.<\/div>\n<div>Les propri\u00e9t\u00e9s suivantes sont d\u00e9finies dans la norme EN 14041 pour les rev\u00eatements de sol.<\/div>\n<div>\n<ul>\n<li>Comportement au feu<\/li>\n<li>Teneur en pentachloroph\u00e9nol (PCP)<\/li>\n<li>\u00c9missions de formald\u00e9hyde (HCHO)<\/li>\n<li>Comportement de glissement<\/li>\n<li>Comportement \u00e9lectrique (conductivit\u00e9)<\/li>\n<li>Comportement \u00e9lectrique (conductivit\u00e9)<\/li>\n<li>Comportement \u00e9lectrique (antistatique)<\/li>\n<li>Conductivit\u00e9 thermique<\/li>\n<li>R\u00e9sistance \u00e0 l&rsquo;eau\n<\/li>\n<\/ul>\n<p>Si le fabricant ne pr\u00e9cise pas une propri\u00e9t\u00e9 essentielle, celle-ci doit \u00eatre marqu\u00e9e NPD (No Performance Declared).<\/p><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Comportement au feu \/ Classement de r\u00e9sistance au feu<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Les mat\u00e9riaux de construction sont en r\u00e8gle g\u00e9n\u00e9rale class\u00e9s en fonction de leur comportement au feu. Les r\u00e9sultats des essais pour la cat\u00e9gorisation et la classification de la classe de r\u00e9sistance au feu sont r\u00e9partis de la mani\u00e8re suivante:<\/p>\n<ul>\n<li>ininflammable<\/li>\n<li>difficilement inflammable<\/li>\n<li>moyennement inflammable<\/li>\n<li>facilement inflammable<\/li>\n<\/ul>\n<p>La norme europ\u00e9enne EN\u00a013501-1 classe les rev\u00eatements de sol selon des niveaux encore plus \u00e9chelonn\u00e9s avec les lettres A (incombustible) \u00e0 F (facilement inflammable). Les rev\u00eatements de sol textiles sont caract\u00e9ris\u00e9s par l\u2019indice suppl\u00e9mentaire \u00ab\u00a0fl\u00a0\u00bb pour \u00ab\u00a0florings\u00a0\u00bb et sont majoritairement affect\u00e9s aux classes \u00ab\u00a0B-fl\u00a0\u00bb, \u00ab\u00a0C-fl\u00a0\u00bb et \u00ab\u00a0E-fl\u00a0\u00bb. B-fl est la classe de r\u00e9sistance au feu la plus exigeante qui est uniquement prescrite dans les zones pr\u00e9sentant des exigences particuli\u00e8res comme, entre autres, les issues de secours dans les h\u00f4tels ou les salles de travail dans les b\u00e2timents publics et administratifs. La classe \u00ab\u00a0E-fl\u00a0\u00bb est en r\u00e8gle g\u00e9n\u00e9rale suffisante dans le secteur priv\u00e9. Les classes de r\u00e9sistance au feu respectives sont repr\u00e9sent\u00e9es de mani\u00e8re facilement identifiable \u00e0 l&rsquo;aide de pictogrammes.<\/p>\n<p>La classification d&rsquo;un rev\u00eatement de sol textile s\u2019appuie \u00e9galement sur un autre crit\u00e8re qui est l&rsquo;\u00e9tat de pose en combinaison avec le produit concern\u00e9. On emploie des abr\u00e9viations pour indiquer l&rsquo;\u00e9tat de pose dans lequel le rev\u00eatement de sol (textile) correspondant a \u00e9t\u00e9 test\u00e9. Les lettres suivantes indiquent l\u2019\u00e9tat de pose respectif:<\/p>\n<ul>\n<li><strong>L<\/strong>\u00a0= pose libre (loose laid)<\/li>\n<li><strong>G<\/strong>\u00a0= coll\u00e9 (glued)<\/li>\n<li><strong>CS<\/strong>\u00a0= support inflammable (combustible substrate)<\/li>\n<li><strong>NCS<\/strong>\u00a0= support ininflammable (non-combustable substrate)<\/li>\n<\/ul>\n<p>Pour en savoir plus sur le th\u00e8me des classes de r\u00e9sistance au feu en lien avec les rev\u00eatements de sol textiles, cliquez ici.<\/p>\n<p class=\"p1\"><span class=\"s1\"><a href=\"https:\/\/gut-prodis.eu\/fr\/test-de-produit\/retardateurs-de-flammes\">Vous trouverez de plus amples informations sur le th\u00e8me des classes de feu et des rev\u00eatements de sol textiles ici.<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Exemples de pictogrammes de classes de r\u00e9sistance au feu<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Par souci de clart\u00e9, nous avons ici uniquement int\u00e9gr\u00e9s des exemples et un graphique qui explique les diff\u00e9rents composants du marquage pour le classement de r\u00e9sistance au feu.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/erklaerung-fcss-piktogramme-brandklassen-teppichboeden.jpg\u00a0\u00bb title_text=\u00a0\u00bberklaerung-fcss-piktogramme-brandklassen-teppichboeden\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb40%\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-bfl-s1-l-cs.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-bfl-s1-l-cs\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-cfl-s1-g-ncs.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-cfl-s1-g-ncs\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-dfl-s2-g-cs.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-dfl-s2-g-cs\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||50px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||100px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||100px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb0px||1px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Propri\u00e9t\u00e9s \u00e9lectriques<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4 class=\"sppb-addon-title\">Conductivit\u00e9<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Les rev\u00eatements de sol textiles sont consid\u00e9r\u00e9s comme dissipateurs (antistatique) selon la norme EN\u00a014041 si la r\u00e9sistance au passage ou la r\u00e9sistance superficielle est \u2264 109\u00a0\u03a9. Cette caract\u00e9ristique est particuli\u00e8rement importante dans les zones o\u00f9 un rev\u00eatement de sol antistatique est indispensable pour exclure les d\u00e9charges \u00e9lectrostatiques comme, entre autres, dans les salles d&rsquo;op\u00e9ration, les salles de chirurgie \u00e0 haute fr\u00e9quence ou les salles informatiques.<\/p>\n<p><strong>D\u00e9finitions selon EN\u00a014041\u00a0:<\/strong><\/p>\n<ul>\n<li>Rev\u00eatements de sol dissipateurs de charges d\u2019\u00e9lectricit\u00e9 statique\u00a0: r\u00e9sistance au passage \u2264 109\u2126 (ISO 10965)<\/li>\n<li>Rev\u00eatements de sol conducteurs\u00a0: r\u00e9sistance au passage \u2264 106\u2126 (ISO 10965)<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-electricalbehaviour-1061.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-electricalbehaviour-1061&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Rev\u00eatement de sol conducteur<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-electricalbehaviour-1091.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-electricalbehaviour-1091&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Rev\u00eatement de sol dissipateur de charges d\u2019\u00e9lectricit\u00e9 statique<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4 class=\"sppb-addon-title\">Antistatique<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Le symbole indique qu\u2019une charge \u00e9lectrique potentielle (tension au niveau du corps) sera directement d\u00e9charg\u00e9e par le rev\u00eatement de sol.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-electricalbehaviour-20.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-electricalbehaviour-20&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb20%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>R\u00e9sistance au glissement<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La norme EN\u00a014041 sp\u00e9cifie que les moquettes doivent r\u00e9pondre \u00e0 certains aspects de s\u00e9curit\u00e9, dont fait partie la r\u00e9sistance au glissement. Selon cette norme, les rev\u00eatements de sol textiles doivent pr\u00e9senter en \u00e9tat sec et propre un coefficient de frottement dynamique &gt;\u00a00,3. Si cette condition est remplie, le produit peut porter le symbole \u00ab\u00a0DS\u00a0\u00bb et, dans le cas contraire, il doit \u00eatre \u00e9tiquet\u00e9 avec le symbole NPD (No Performance Declared\u00a0; \u00ab\u00a0aucune information de r\u00e9sistance au glissement possible).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-slip_resistance-ds.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-slip_resistance-ds\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>DS (declared Slip)<br \/><\/strong>nouvelle ic\u00f4ne<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-_030.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-_030&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>DS (declared Slip) \u22650,3<br \/><\/strong>nouvelle ic\u00f4ne<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-slip_resistance-npd.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-slip_resistance-npd\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>NPD (No Performance Declared)<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Classes d\u2019\u00e9missions de formald\u00e9hyde<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Pouvant \u00eatre pr\u00e9sent en petites quantit\u00e9s sous forme d\u2019impuret\u00e9s issues de l\u2019environnement (origine naturelle), de produit de r\u00e9action pendant la production ou comme composant de la recette du produit, le formald\u00e9hyde peut \u00eatre d\u00e9tect\u00e9 par des tests d&rsquo;\u00e9mission. Les rev\u00eatements de sol textiles contenant du formald\u00e9hyde g\u00e9n\u00e9r\u00e9 ou ajout\u00e9 pendant la production doivent \u00eatre test\u00e9s. Apr\u00e8s avoir \u00e9t\u00e9 test\u00e9s selon la norme ENV\u00a0717-1 ou ENV\u00a0717-2, les rev\u00eatements de sol contenant du formald\u00e9hyde sont affect\u00e9s aux classes E1 (ENV\u00a0717-1 \u2264 0,13\u00a0mg\/m\u00b3 et ENV\u00a0717-2 \u2264 3,5\u00a0mg\/m\u00b2h) ou E2 (ENV\u00a0717-1 &gt; 0,13\u00a0mg\/m\u00b3 et ENV\u00a0717-2 &gt; 3,5 &lt; 8,0\u00a0mg\/m\u00b2h). Cette exigence de test ne s&rsquo;applique pas aux rev\u00eatements de sol qui font l\u2019objet d\u2019aucun ajout de mat\u00e9riaux contenant du formald\u00e9hyde au cours de la production ou du traitement ult\u00e9rieur. Le classement de tels produits n\u2019est pas requis, mais ils peuvent cependant \u00eatre affect\u00e9s \u00e0 la classe E1 sans test.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb%221_3%22,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bb%22default%22&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb%2220px||||false|false%22&Prime; hover_enabled=\u00a0\u00bb%220%22&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb%221_3%22&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bb%22default%22&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-formaldehyde-emission-e1.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-formaldehyde-emission-e1&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bb%22default%22&Prime; max_width=\u00a0\u00bb42%\u00a0\u00bb custom_margin=\u00a0\u00bb||29px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bb%22default%22&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe d\u2019\u00e9missions E1<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-formaldehyde-emission-e2.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-formaldehyde-emission-e2&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb custom_margin=\u00a0\u00bb||29px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Classe d\u2019\u00e9missions E2<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-formaldehyde-emission-na.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-formaldehyde-emission-na\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||35px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Aucun ajout de formald\u00e9hyde (NA = not added)<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4 class=\"sppb-addon-title\">Teneur en pentachloroph\u00e9nol<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Le pentachloroph\u00e9nol (PCP) est l&rsquo;un des principaux produits chimiques environnementaux en raison de sa toxicit\u00e9, de sa contamination par les dioxines et de sa large diffusion. Ces derni\u00e8res ann\u00e9es, la pollution de l&rsquo;environnement et l&rsquo;exposition de base de la population en g\u00e9n\u00e9ral ont diminu\u00e9, du moins en R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Allemagne. Le probl\u00e8me m\u00e9dical environnemental qui reste \u00e0 r\u00e9soudre r\u00e9side dans l&rsquo;utilisation ant\u00e9rieure de produits de pr\u00e9servation du bois contenant du PCP dans les espaces de vie.<br \/>Par cons\u00e9quent, la teneur en PCP des rev\u00eatements de sol est r\u00e9glement\u00e9e. Le pictogramme DL (PCP) indique que le contenu du PCP est inf\u00e9rieur au seuil de d\u00e9tection (DL).<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-pcp_emission-dl.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-pcp_emission-dl\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb20%\u00a0\u00bb max_width_tablet=\u00a0\u00bb50%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"column-wrap-id-1604330239123\" class=\"sppb-col-md-4\">\n<div id=\"column-id-1604330239123\" class=\"sppb-column\">\n<div class=\"sppb-column-addons\">\n<div id=\"sppb-addon-wrapper-1604335466856\" class=\"sppb-addon-wrapper\">\n<div id=\"sppb-addon-1604335466856\" class=\"clearfix \">\n<div class=\"sppb-addon sppb-addon-text-block sppb-text-center \">\n<div class=\"sppb-addon-content\">\n<div id=\"column-wrap-id-1604330239123\" class=\"sppb-col-md-4\">\n<div id=\"column-id-1604330239123\" class=\"sppb-column\">\n<div class=\"sppb-column-addons\">\n<div id=\"sppb-addon-wrapper-1604335466856\" class=\"sppb-addon-wrapper\">\n<div id=\"sppb-addon-1604335466856\" class=\"clearfix \">\n<div class=\"sppb-addon sppb-addon-text-block sppb-text-center \">\n<div class=\"sppb-addon-content\"><strong>Contenu du PCP<br \/><\/strong>en dessous du seuil de d\u00e9tection<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"column-wrap-id-1604330239124\" class=\"sppb-col-md-4\">\n<div id=\"column-id-1604330239124\" class=\"sppb-column\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"column-wrap-id-1604330239124\" class=\"sppb-col-md-4\">\n<div id=\"column-id-1604330239124\" class=\"sppb-column\">\u00a0<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Conductivit\u00e9 thermique<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>En cas d\u2019utilisation d\u2019un chauffage par le sol en combinaison avec la pose ou l\u2019utilisation de rev\u00eatements de sol textiles, la r\u00e9sistance thermique (au moins 0,5\u00a0m\u00b2K\/W, selon la norme EN\u00a012667:2001) de la moquette doit \u00eatre aussi faible que possible. Ce pictogramme indique si le rev\u00eatement de sol peut \u00eatre utilis\u00e9 avec un sol chauffant.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-thermal_resistance.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-thermal_resistance\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Ancien pictogramme<\/p>\n<p>Chauffage au sol, adapt\u00e9<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-y-23.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-y-23&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Conductivit\u00e9 thermique<\/strong><br \/>\u00e0 23 \u00b0C<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-outl-r-23.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-outl-r-23&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>R\u00e9sistance thermique<\/strong><br \/>\u00e0 23\u00b0 C<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; header_4_font=\u00a0\u00bb|600|||||||\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4 class=\"sppb-addon-title\">Autres pictogrammes et aptitudes compl\u00e9mentaires<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-dimensional-stability.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-dimensional-stability\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Modification dimensionnelle \/ Stabilit\u00e9 dimensionnelle<\/strong><\/p>\n<p>Stabilit\u00e9 dimensionnelle &#8211; les dalles de moquette pos\u00e9es non coll\u00e9es doivent r\u00e9pondre \u00e0 des exigences suppl\u00e9mentaires en termes de comportement au r\u00e9tr\u00e9cissement et \u00e0 la dilatation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-roll-length.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-roll-length\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Longueur du rouleau<\/strong><br \/>Sp\u00e9cification de la longueur du rouleau<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-roll-width.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-roll-width\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Largeur du rouleau<br \/><\/strong>Sp\u00e9cification de la\u00a0largeur du rouleau<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/produktpass-teppichboden.de\/wp-content\/uploads\/2023\/11\/fcss-tile-size.jpg\u00a0\u00bb title_text=\u00a0\u00bbfcss-tile-size\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Dimension\u00a0: taille des dalles<\/strong><\/p>\n<p>Indication des dimensions d\u2019une dalle de moquette individuelle.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||50px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||100px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||100px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb0px||49px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb65px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00a0\u00bbabkuerzungen\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#23295B\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#154689&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 class=\"sppb-addon-title\">R\u00e9pertoire des abr\u00e9viations<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Beaucoup d&rsquo;informations ou de mots que vous trouvez sur notre site web sont abr\u00e9g\u00e9s par souci de simplicit\u00e9. Le r\u00e9pertoire des abr\u00e9viations suivant vous explique leurs significations.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li>\n<div><strong>AgBB<\/strong>\u00a0= Ausschuss zur gesundheitlichen Bewertung von Baumaterialien (Commission d\u2019\u00e9valuation sanitaire des produits de construction)\u00a0;\u00a0<a href=\"https:\/\/www.umweltbundesamt.de\/en\/topics\/health\/commissions-working-groups\/committee-for-health-related-evaluation-of-building\" target=\"_blank\" rel=\"noopener noreferrer\">informations compl\u00e9mentaires<\/a><\/div>\n<\/li>\n<li>\n<div><strong>CE<\/strong>\u00a0(label\u00a0\/ marquage) = Conformit\u00e9 Europ\u00e9enne (FR)\u00a0; Europ\u00e4ische Konformit\u00e4t (DE)<\/div>\n<\/li>\n<li>\n<div><strong>EPD\u00a0<\/strong>= Environmental Product Declaration (EN)\u00a0; D\u00e9claration environnementale produit (FR)<\/div>\n<\/li>\n<li>\n<div><strong>FCSS<\/strong>\u00a0= Floor Covering Standard Symbols (EN)\u00a0; symboles normalis\u00e9s pour les rev\u00eatements de sol (FR)<\/div>\n<\/li>\n<li>\n<div><strong>GUT<\/strong>\u00a0= Gemeinschaft umweltfreundlicher Teppichboden e.V. (Association des moquettes respectueuses de l\u2019environnement)<\/div>\n<\/li>\n<li>\n<div><strong>IAP\u00a0<\/strong>= Indoor Air Pollution (EN)\u00a0; pollution de l\u2019air int\u00e9rieur (FR)<\/div>\n<\/li>\n<li>\n<div><strong>IAQ<\/strong>\u00a0= Indoor Air Quality (EN)\u00a0; qualit\u00e9 de l\u2019air int\u00e9rieur (FR)<\/div>\n<\/li>\n<li>\n<div><strong>LCI<\/strong>\u00a0= Lowest Concentration of Interest EN)\u00a0; CLI ou Concentration Limite d\u2019Int\u00e9r\u00eat (FR)<\/div>\n<\/li>\n<li>\n<div><strong>POP<\/strong>\u00a0= Persistant organic Pollutants (EN)\u00a0; polluants organiques persistants (FR)<\/div>\n<\/li>\n<li>\n<div><strong>PRODIS<\/strong>\u00a0= Produktinformationssystem (Syst\u00e8me d\u2019information sur les produits)<\/div>\n<\/li>\n<li>\n<div><strong>REACH<\/strong>\u00a0= Registration, Evaluation, Authorisation and Restriction of Chemicals (EN)\u00a0; Enregistrement, \u00e9valuation, autorisation et restriction des substances chimiques (FR)<\/div>\n<\/li>\n<li>\n<div><strong>SVHC<\/strong>\u00a0= Substances of Very High Concern (EN)\u00a0; substances extr\u00eamement pr\u00e9occupantes (FR)<\/div>\n<\/li>\n<li>\n<div><strong>VOC\u00a0<\/strong>= Volatile Organic\u00a0Compounds (EN)\u00a0; compos\u00e9s organiques volatils (COV) (FR)<\/div>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informations utilessur les moquettesD\u00e9couvrez ici des informations importantes sur les rev\u00eatements de sol textiles : pour le choix d\u2019une moquette ad\u00e9quate, sur le nettoyage et l&rsquo;entretien ainsi que sur le march\u00e9 des moquettes dans l&rsquo;Union europ\u00e9enne.Types de moquettesRev\u00eatements de sol textiles Les moquettes sont des rev\u00eatements de sol textiles. Selon la norme DIN ISO 2424, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"dipi_cpt_category":[],"class_list":["post-1670","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informations sur les moquettes\u00a0: faits, conseils et astuces<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d&#039;usage, jusqu\u2019au march\u00e9 des moquettes dans l&#039;UE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informations sur les moquettes\u00a0: faits, conseils et astuces\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d&#039;usage, jusqu\u2019au march\u00e9 des moquettes dans l&#039;UE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/\" \/>\n<meta property=\"og:site_name\" content=\"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T12:02:34+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"51 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/informations-utiles\\\/\",\"url\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/informations-utiles\\\/\",\"name\":\"Informations sur les moquettes\u00a0: faits, conseils et astuces\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#website\"},\"datePublished\":\"2023-11-17T11:29:49+00:00\",\"dateModified\":\"2024-01-22T12:02:34+00:00\",\"description\":\"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d'usage, jusqu\u2019au march\u00e9 des moquettes dans l'UE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/informations-utiles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/informations-utiles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/informations-utiles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"informations-utiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/\",\"name\":\"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#organization\",\"name\":\"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)\",\"url\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gut-prodis.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/gut-teppichboden-logo.svg\",\"contentUrl\":\"https:\\\/\\\/gut-prodis.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/gut-teppichboden-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)\"},\"image\":{\"@id\":\"https:\\\/\\\/gut-prodis.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gut-ev\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informations sur les moquettes\u00a0: faits, conseils et astuces","description":"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d'usage, jusqu\u2019au march\u00e9 des moquettes dans l'UE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/","og_locale":"fr_FR","og_type":"article","og_title":"Informations sur les moquettes\u00a0: faits, conseils et astuces","og_description":"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d'usage, jusqu\u2019au march\u00e9 des moquettes dans l'UE.","og_url":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/","og_site_name":"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)","article_modified_time":"2024-01-22T12:02:34+00:00","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"51 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/","url":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/","name":"Informations sur les moquettes\u00a0: faits, conseils et astuces","isPartOf":{"@id":"https:\/\/gut-prodis.eu\/fr\/#website"},"datePublished":"2023-11-17T11:29:49+00:00","dateModified":"2024-01-22T12:02:34+00:00","description":"D\u00e9couvrez des informations utiles\u00a0: du choix de la bonne moquette, en passant par les classes d'usage, jusqu\u2019au march\u00e9 des moquettes dans l'UE.","breadcrumb":{"@id":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gut-prodis.eu\/fr\/informations-utiles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gut-prodis.eu\/fr\/informations-utiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gut-prodis.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"informations-utiles"}]},{"@type":"WebSite","@id":"https:\/\/gut-prodis.eu\/fr\/#website","url":"https:\/\/gut-prodis.eu\/fr\/","name":"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)","description":"","publisher":{"@id":"https:\/\/gut-prodis.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gut-prodis.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gut-prodis.eu\/fr\/#organization","name":"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)","url":"https:\/\/gut-prodis.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gut-prodis.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/gut-prodis.eu\/wp-content\/uploads\/2023\/10\/gut-teppichboden-logo.svg","contentUrl":"https:\/\/gut-prodis.eu\/wp-content\/uploads\/2023\/10\/gut-teppichboden-logo.svg","width":1,"height":1,"caption":"Gemeinschaft umweltfreundlicher Teppichboden e.V. (GUT)"},"image":{"@id":"https:\/\/gut-prodis.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/gut-ev\/"]}]}},"_links":{"self":[{"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/pages\/1670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/comments?post=1670"}],"version-history":[{"count":3,"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/pages\/1670\/revisions"}],"predecessor-version":[{"id":4026,"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/pages\/1670\/revisions\/4026"}],"wp:attachment":[{"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/media?parent=1670"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/gut-prodis.eu\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=1670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}